{"id":12578,"date":"2022-08-08T13:05:18","date_gmt":"2022-08-08T13:05:18","guid":{"rendered":"https:\/\/vagabondogs.me\/\/?p=12578"},"modified":"2022-11-11T12:47:46","modified_gmt":"2022-11-11T12:47:46","slug":"das-richtige-hundefutter","status":"publish","type":"post","link":"https:\/\/vagabondogs.me\/de\/blog\/das-richtige-hundefutter\/","title":{"rendered":"Das richtige Hundefutter"},"content":{"rendered":"\n<h4 class=\"wp-block-heading\">Das richtige Hundefutter ist DIE Grundlage der Hundegesundheit.<\/h4>\n\n\n\n<p>Nicht nur der k\u00f6rperlichen. Auch der psychischen. Und sogar der erzieherischen.<\/p>\n\n\n\n<p>Denn je besser der Hund mit allen N\u00e4hrstoffen versorgt ist, desto souver\u00e4ner kann sein Nervensystem mit Stressfaktoren umgehen und \u00fcberschie\u00dfende Reaktionen ausgleichen. Ein Mangel an bestimmten N\u00e4hrstoffen &#8211; kann und wird &#8211; die nervliche Sensibilit\u00e4t verst\u00e4rken und dem Hund das Leben schwerer machen.<\/p>\n\n\n\n<p>Zudem senkt gutes Essen das Frustrationsempfinden. Weil es Spa\u00df macht. Vor allem dann, wenn die Welt mit der Nase wahrgenommen wird und man einen, dank des galaktischen Riechkolbens, tausendfach besseren Geschmackssinn hat, als der Mensch.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/10\/DSC05675-1024x683.jpg\" alt=\"\" class=\"wp-image-13107\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/10\/DSC05675-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/10\/DSC05675-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/10\/DSC05675-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/10\/DSC05675-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/10\/DSC05675.jpg 1500w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1001\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC05452.jpg\" alt=\"\" class=\"wp-image-12582\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC05452.jpg 1500w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC05452-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC05452-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC05452-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC05452-360x240.jpg 360w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h4 class=\"wp-block-heading\">Der Mythos des schlechten Essers<\/h4>\n\n\n\n<p>Der Hund kennt den Unterschied zwischen unserem Steakhouseburger und seinem Trockenfutterelend. Und erlebt nicht selten ein aktives Unrechtsbewusstsein. Erlebt Frustration. Schon dutzendfach im Zuge unserer vielen Haussits mit unseren eigenen Hunden erlebt.<\/p>\n\n\n\n<p>Die Betreuungshunde bekommen meist billiges Trockenfutter oder ein dubioses Nassfutter-Trockenfutter-Gemisch, welches nur wenige von ihnen gut fressen. Bekommen sie mit, dass ich meinen Hunden echte Lebensmittel serviere, verweigern sie ihr eigenes Napfelend g\u00e4nzlich.<\/p>\n\n\n\n<p>Aus schlechten Essern werden Futterverweigerer. Protestierende, bellende, jaulende Futterverweigerer. W\u00fctende Futterverweigerer. Beleidigte Futterverweigerer. Und das nur, weil sie mitbekommen, dass anderen Hunden echte Nahrung serviert wird. Das ist pures Ich-Bewusstsein! Unrechtsbewusstsein.<\/p>\n\n\n\n<p>Nein, sie sind keine schlechten Esser, wie oft von ihren Besitzern betitelt. Das Fertigfutter h\u00e4ngt ihnen ganz einfach zum Halse raus! Und sie tun mir verdammt leid, denn ich lebe w\u00e4hrend meiner Arbeit als Haussitterin eng mit ihnen zusammen und bin gezwungen, in zwei Welten zu f\u00fcttern.<\/p>\n\n\n\n<p>Meine eigenen Hunde f\u00fcttere ich grunds\u00e4tzlich au\u00dfer Sichtweite der &#8220;schlechten Esser&#8221;. Alles andere w\u00e4re Folter und zu einer Futterumstellung bin ich als Hundesitterin nicht berechtigt.<\/p>\n\n\n\n<p>Eine Schande nenne ich es, dem Hund eine der ihm wichtigsten Dinge seiner Existenz zu verwehren: Echte Lebensmittel.<\/p>\n\n\n\n<p>Wer mir nicht glaubt, setzt sich vor den Fernseher und macht eine T\u00fcte Chappi auf. F\u00fcr sich selbst nat\u00fcrlich, nicht f\u00fcr den Hund.<\/p>\n\n\n\n<p>Schmeckt nicht? Ist eklig? Sind tausend komische Sachen drin?<br>Findet der Hund auch!<\/p>\n\n\n\n<p>Doch ihr k\u00f6nnt w\u00e4hlen. Ihr k\u00f6nnt das Elend gemeinsam beenden.<br>F\u00fcr welche Seite des Buffets entscheidet ihr euch?<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1001\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04364.jpg\" alt=\"\" class=\"wp-image-12584\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04364.jpg 1500w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04364-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04364-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04364-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04364-360x240.jpg 360w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Wissenschaftliches f\u00fcr den gemeinen Hundefreund<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/little-red-riding-hood-7361774_640.png\" alt=\"\" class=\"wp-image-12650\" width=\"299\" height=\"235\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/little-red-riding-hood-7361774_640.png 640w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/little-red-riding-hood-7361774_640-300x236.png 300w\" sizes=\"auto, (max-width: 299px) 100vw, 299px\" \/><\/figure>\n<\/div>\n\n\n<ul class=\"wp-block-list\"><li>Der Wolf ist ein Karnivore, ein Fleischfresser.<\/li><li>Der Hund ist, wissenschaftlich gesehen, eine Mischung aus Karnivore, dem Fleischfresser, und dem Omnivore, dem Allesfresser.<\/li><li>Der Hund lebt seit 30.000 Jahren mit dem Menschen zusammen.<\/li><li>Der Hund kann, rasseabh\u00e4ngig, St\u00e4rke verdauen.<\/li><li>Der Hund hat, rasseabh\u00e4ngig, die F\u00e4higkeit zu Mahlbewegungen des Kiefers entwickelt, durch die Ausbildung eines leicht eingedrehten Kiefergelenks.<\/li><li>Die Backenz\u00e4hne sind, rasseabh\u00e4ngig, \u00e4hnlich bunodonten Molaren,\u00a0leicht abgerundet, um ein gewisses Zermahlen pflanzlicher Nahrung zu erm\u00f6glichen.<\/li><li>Der Hundedarm ist, rasseabh\u00e4ngig, l\u00e4nger als der des Wolfes. Fast so lang wie der Menschendarm.<\/li><li>Der Hund kann Zellulose nicht aufspalten. Deshalb sollte pflanzliche Kost p\u00fcriert werden.<\/li><li>Der Hund kann kein Vitamin D \u00fcber die Haut bilden, sondern ben\u00f6tigt Vitamin D aus der Nahrung.<\/li><li>Der Hund kann die f\u00fcr die Fettverdauung wichtige Gallens\u00e4ure nur bei ausreichender Anwesenheit der Aminos\u00e4ure Taurin bilden.<\/li><li>Der Hund ben\u00f6tigt ausreichend Arginin, um sein Stickstoffgleichgewicht aufrechtzuerhalten.<\/li><\/ul>\n\n\n\n<p>Die h\u00e4lfte der Punkte sind typisch omnivor. Die andere H\u00e4lfte der Punkte sind typisch karnivor. Je nach Rasse tendiert der Hund mehr in die eine oder die andere Richtung.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Warum rasseabh\u00e4ngig?<\/h5>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/dogs-4189517-2-1-300x200.jpg\" alt=\"\" class=\"wp-image-12647\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/dogs-4189517-2-1-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/dogs-4189517-2-1-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/dogs-4189517-2-1-768x512.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/dogs-4189517-2-1-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/dogs-4189517-2-1.jpg 1501w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Weil die Umformung des Hundek\u00f6rpers in Abh\u00e4ngigkeit vom Nahrungsangebot der domestizierenden menschlichen Kultur stand. Und nicht jede Kultur a\u00df \u00fcberall dasselbe.<\/p>\n\n\n\n<p><strong>Beispiel Husky<\/strong><\/p>\n\n\n\n<p>Nordische Rassen wurden von V\u00f6lkern des hohen Nordens domestiziert. Sibirien, Alaska, Kanada etc. Dort a\u00dfen die Menschen \u00fcber Jahrtausende hinweg haupts\u00e4chlich Fleisch und Fisch. Der K\u00f6rper nordischer Rassen ist an eine hochgradig fleischlastige Ern\u00e4hrung angepasst, \u00e4hnlich der des Wolfes. Die St\u00e4rkeverdauung ist deutlich schlechter ausgepr\u00e4gt als jene der typischen Begleithunde des Westens.<\/p>\n\n\n\n<p><strong>Beispiel Herdenschutzhund<\/strong><\/p>\n\n\n\n<p>Herdenschutzhunde wurden und werden in ihren Ursprungsl\u00e4ndern meist mit Getreidebrei und Brot gef\u00fcttert. Fleisch gibt es seltener. Entsprechend ist ihre Verdauung auf Kohlenhydrate ausgerichtet. Herdiexperten sprechen von einem maximalen Fleischanteil von 50 %.<\/p>\n\n\n\n<p><strong>Beispiel westlicher Allesfresser<\/strong><\/p>\n\n\n\n<p>Hunderassen der westlichen Breitengerade sind in der Regel an eine omnivore Ern\u00e4hrung angepasst. An das, was Gro\u00dfvater im Wald erlegte und Gro\u00dfmutter am Feld aufklaubte.<\/p>\n\n\n\n<p>Allen Statistiken zum Trotz muss ausprobiert werden, was der individuelle Hund vertr\u00e4gt. Zu gro\u00df ist die Durchmischung der einzelnen Rassen. Zu verzweigt der Stammbaum. Zu gering das Allwissen der Menschheit.<\/p>\n\n\n\n<p>Ein Schema F existiert nur im Hinblick auf eine Sache: Echte Lebensmittel sind besser, als das, was nach der siebten Fabrik von ihnen \u00fcbrig blieb.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Wie ich (auf Reisen) f\u00fcttere<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1001\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04302-1.jpg\" alt=\"\" class=\"wp-image-12588\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04302-1.jpg 1500w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04302-1-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04302-1-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04302-1-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04302-1-360x240.jpg 360w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n<\/div>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"554\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/aaa-scaled.jpg\" alt=\"\" class=\"wp-image-12590\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/aaa-scaled.jpg 2560w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/aaa-300x65.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/aaa-1024x222.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/aaa-768x166.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/aaa-1536x332.jpg 1536w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/aaa-2048x443.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div>\n\n\n<p>&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Ich orientiere mich seit Jahren am Konzept von Paleo Low-Carb.<\/h5>\n\n\n\n<p>F\u00fcr mich selbst und f\u00fcr meine Hunde. Das bedeutet, wann immer m\u00f6glich, frische, unverarbeitete, echte Lebensmittel, in Bio- und Weidetierqualit\u00e4t.<\/p>\n\n\n\n<p>90 % der Zeit koche ich f\u00fcr meine Hunde.<\/p>\n\n\n\n<p>Morgens bekommen sie frisches Fleisch und abends frisch gekochtes Gem\u00fcse. Meinen genauen Kochplan erl\u00e4utere ich weiter unten im Text.<\/p>\n\n\n\n<p>Je nach Land, Reiseplan, Kochm\u00f6glichkeiten oder auch an Umzugstagen, ist kochen nicht m\u00f6glich. Dann greife ich auf eine gute Nassfutterdose zur\u00fcck.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04642-300x200.jpg\" alt=\"\" class=\"wp-image-12592\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04642-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04642-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04642-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04642-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04642.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Gut bedeutet in meinen Augen, dass die Dose ausschlie\u00dflich echtes Fleisch und echtes Gem\u00fcse, mit einem Fleischanteil zwischen 50 und 80 %, enth\u00e4lt. Sie muss offen deklariert sein und darf absolut keinen Quatsch wie Zucker, Konservierungsstoffe, Geschmacksverst\u00e4rker oder solche Sp\u00e4\u00dfe wie \u201epflanzliche und tierische Nebenerzeugnisse\u201c enthalten.<\/p>\n\n\n\n<p>Ich nutze z.B. die Marken Herrmanns, Defu und Terra Canis.<\/p>\n\n\n\n<p>In Gro\u00dfbritannien nutzen wir das Nassfutter von Lily\u2019s Kitchen.<\/p>\n\n\n\n<p>Langfristig w\u00fcrde ich kein Dosenfutter f\u00fcttern. Dosen sind f\u00fcr mich eine \u00dcbergangsl\u00f6sung, wenn mir auf Reisen keine Kochm\u00f6glichkeit zur Verf\u00fcgung steht.<\/p>\n\n\n\n<p>Trockenfutter jeglicher Art lehnen wir grunds\u00e4tzlich ab. Genauso wie geschlossen deklarierte Produkte und Futter von Firmen a la Pedigree, Chappi und deren b\u00f6se Br\u00fcder.<\/p>\n\n\n\n<p>F\u00fcrs Protokoll: Ich kaufe alle genannten Produkte aus \u00dcberzeugung und werde von keiner Firma bezahlt.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Kochen f\u00fcr den Hund \u2013 Die Wissensgrundlagen<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1001\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04332.jpg\" alt=\"\" class=\"wp-image-12594\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04332.jpg 1500w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04332-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04332-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04332-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04332-360x240.jpg 360w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n<\/div>\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Der Proteinbedarf <\/strong><\/h5>\n\n\n\n<p>Der Proteinbedarf des Hundes liegt, je nach Rasse, bei 2 &#8211; 6 g\/kg.<\/p>\n\n\n\n<p>Tierisches Protein hat eine deutlich bessere Bioverf\u00fcgbarkeit als pflanzliches Protein. Es weist, aus guter Quelle, sogar eine h\u00f6here N\u00e4hrstoffdichte auf.<\/p>\n\n\n\n<p>Zu viel Protein kann die Nieren \u00fcbers\u00e4uern und wird ungenutzt wieder ausgeschieden.<\/p>\n\n\n\n<p>Der Fleischanteil im Futter muss an den Bedarf des einzelnen Hundes angepasst werden. Ein m\u00f6glichst hoher Fleischanteil ist kein Pr\u00e4dikat f\u00fcr gutes Futter.<\/p>\n\n\n\n<p>Ich f\u00fcttere einen Fleischanteil von 50 %. Dieser deckt den Proteinbedarf meiner Hunde mit 4 g\/kg gut ab. So bleibt zudem noch ein bisschen Spielraum f\u00fcr ein paar Kausnacks.<\/p>\n\n\n\n<p>Einmal pro Woche ersetze ich eine Fleischmahlzeit durch die gleiche Menge an Ei. Das Eiwei\u00df erhitze ich, da rohes Eiwei\u00df Hunden nicht gut bekommt. Eigelb kann roh gef\u00fcttert werden.<\/p>\n\n\n\n<p>Meine Hunde sind sowohl rohes, als auch gegartes Fleisch gewohnt. Rohes und gegartes Fleisch sollten jedoch nie zusammen im Napf landen. Das gibt Magenkirmes.<\/p>\n\n\n\n<p>Achtung: Bitte kein Schwein oder Wildschwein f\u00fcttern. Es kann das Aujeszky-Virus&nbsp;enthalten, welches f\u00fcr Menschen harmlos und f\u00fcr Hunde und Katzen t\u00f6dlich ist.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Muskelfleisch<\/h5>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/Bildschirmfoto-2022-08-08-um-14.27.59-300x200.jpg\" alt=\"\" class=\"wp-image-12628\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Bildschirmfoto-2022-08-08-um-14.27.59-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Bildschirmfoto-2022-08-08-um-14.27.59-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Bildschirmfoto-2022-08-08-um-14.27.59-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Bildschirmfoto-2022-08-08-um-14.27.59-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Bildschirmfoto-2022-08-08-um-14.27.59.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Muskelfleisch soll, mit rund 50%, den Hauptbestandteil der Fleischf\u00fctterung ausmachen und idealerweise gut mit Fett durchzogen sein.<\/p>\n\n\n\n<p>Dabei spreche ich der Einfachheit halber von quergestreifter Muskulatur,&nbsp;bzw. vom Fleisch der Skelettmuskulatur und lasse exotische Varianten wie Zunge und Co au\u00dfen vor. Da wir unser Fleisch auf Reisen aus dem normalen Supermarkt beziehen, ist die Auswahl begrenzt.<\/p>\n\n\n\n<p>Ich achte darauf, dass mind. 50% der Muskelfleischf\u00fctterung aus rotem Fleisch besteht, um den Eisenbedarf der Hunde zu decken.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Organe<\/h5>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04442-300x200.jpg\" alt=\"\" class=\"wp-image-12620\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04442-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04442-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04442-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04442-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04442.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Organe haben eine extrem hohe N\u00e4hrstoffdichte.<\/p>\n\n\n\n<p>Eine Fleischmahlzeit pro Woche besteht bei uns aus Organen. Dabei ist das F\u00fcttern von Leber ein Muss, aufgrund der unerreichten F\u00fclle an Vitaminen und Mineralstoffen. Der Hund hat einen Leberbedarf von 1 &#8211; 2 g\/kg\/Tag bzw. 5% der Gesamtfuttermenge.<\/p>\n\n\n\n<p>Unsere w\u00f6chentliche Organmahlzeit besteht zu mindestens 50% aus Leber. Die andere H\u00e4lfte best\u00fccken wir, je nach Verf\u00fcgbarkeit, mit Milz, Niere oder Herz.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Eier<\/h5>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04468-300x200.jpg\" alt=\"\" class=\"wp-image-12637\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04468-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04468-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04468-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04468-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04468.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Eier sind zum Bersten gef\u00fcllt mit N\u00e4hrstoffen und somit eine willkommene Abwechslung auf dem fleischigen Speiseplan meiner Hunde. Einmal die Woche ersetze ich eine komplette Fleischmahlzeit durch die gleiche Menge an Ei. Das Eigelb kann roh gef\u00fcttert werden. Das Eiklar muss erhitzt werden, da es den Biotinbinder <span>Avidin enth\u00e4lt, welcher im Hund f\u00fcr Biotinmangel sorgen kann. Erhitzen deaktiviert Avidin. Problem gel\u00f6st. Wir erhitzen unsere Eier jedoch komplett, da Tia am liebsten R\u00fchrei isst. Reines Eiwei\u00df ist ihr zu glibberig.\u00a0<\/span><\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Knochen<\/h5>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04488-300x200.jpg\" alt=\"\" class=\"wp-image-12598\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04488-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04488-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04488-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04488-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04488.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Der Calziumbedarf des Hundes liegt bei 50 mg\/kg.<\/p>\n\n\n\n<p>Da eine knochenfreie Hundeern\u00e4hrung den Calziumbedarf nicht deckt, muss Calziumhaltiges zugef\u00fcttert werden.<\/p>\n\n\n\n<p>Als Calziumlieferanten eignen sich rohe, fleischige Knochen am besten. \u201eRoh und fleischig\u201c bedeutet, ein ungef\u00e4hres Knochen-Fleisch-Verh\u00e4ltnis von 1:1.<\/p>\n\n\n\n<p>Blankem, rohem Knochen sollte eine rohe Fleischmahlzeit vorausgegangen sein. Fleisch polstert die Ged\u00e4rme ab und sorgt f\u00fcr die ausreichende Bildung von Magens\u00e4ure.<\/p>\n\n\n\n<p>Knochen d\u00fcrfen ausschlie\u00dflich roh verf\u00fcttert werden. Erhitzte Knochen werden por\u00f6s und splittern. Dies gilt auch f\u00fcr gewolfte Knochen.<\/p>\n\n\n\n<p>K\u00f6nnen ganze oder gewolfte Knochen, aus welchen Gr\u00fcnden auch immer, nicht gef\u00fcttert werden, dann ist Knochenmehl oder Fleischknochenmehl die erste Wahl. Hier muss darauf geachtet werden, dass das Calzium-Phosphor-Verh\u00e4ltnis bei rund 2:1 liegt. Am ehesten findet man dieses Verh\u00e4ltnis bei Fleischknochenmehl.<\/p>\n\n\n\n<p>Liegt das Verh\u00e4ltnis auf gleicher H\u00f6he (wie bei schlechtem Knochenmehl) oder ist massenhaft Calcium, jedoch kein Phosphor vorhanden (wie bei Eierschalenpulver) oder wird deutlich mehr Phosphor als Calcium gef\u00fcttert (wie bei einer reinen Fleischf\u00fctterung ohne Calziumerg\u00e4nzung), kommt es zu einer ung\u00fcnstigen Verschiebung des Mineralstoffhaushaltes, welche den Hund langfristig krankmachen kann.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\"><strong>Gefahren der Knochenf\u00fctterung<\/strong><\/h5>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04515-1-300x200.jpg\" alt=\"\" class=\"wp-image-12633\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04515-1-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04515-1-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04515-1-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04515-1-1536x1025.jpg 1536w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04515-1-2048x1367.jpg 2048w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04515-1-360x240.jpg 360w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Einige Hunde bekommen von Knochen Verstopfung, sogenannten Knochenkot. Knochenkot kann sehr schmerzhaft f\u00fcr Hunde sein und im Extremfall zu einem behandlungsbed\u00fcrftigen Darmverschluss f\u00fchren.<\/p>\n\n\n\n<p>Der Organismus braucht Zeit, um sich an die Knochenverdauung anzupassen. Die F\u00fctterung von Knochen sollte mit Kleinstmengen begonnen und sehr langsam gesteigert werden.<\/p>\n\n\n\n<p>Wird der Kot h\u00e4rter, sollte die Menge zur\u00fcckgeschraubt werden. Tritt Verstopfung auf, sollte die Knochenf\u00fctterung umgehend ausgesetzt werden.<\/p>\n\n\n\n<p>Um die Knochenverdauung zu erleichtern, k\u00f6nnen folgende Schritte versucht werden:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Weiche Knochen von Gefl\u00fcgel und Kleintieren unter Putengr\u00f6\u00dfe bevorzugen. Harte Knochen von Gefl\u00fcgel ab Putengr\u00f6\u00dfe, Lamm, Kalb, Rind, Pferd und Wild, meiden.<\/li><li>Gewolfte Knochen bevorzugen<\/li><li>Die Knochenf\u00fctterung \u00fcber die Woche verteilen, um gr\u00f6\u00dfere Mengen auf einmal zu vermeiden.<\/li><li>Keine blanken, sondern fleischige Knochen f\u00fcttern, damit es besser fluppt. Gemeinsam mit Gem\u00fcsebrei und \u00d6l gef\u00fcttert, fluppt es noch besser.<\/li><li>Ganze Knochen nur an Hunde mit gutem Gebiss und ausreichender Kaut\u00e4tigkeit verf\u00fcttern, ansonsten droht vermehrt Verletzungsgefahr.<\/li><\/ul>\n\n\n\n<p>Wichtig ist zudem, w\u00e4hrend der Knochenf\u00fctterung anwesend zu sein. Knochen k\u00f6nnen im Zahn oder Hals stecken bleiben, was sofortige Hilfe des Besitzers erfordert.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Wir nutzen einmal w\u00f6chentlich eine der folgenden Calciumquellen:<\/strong><\/p>\n\n\n\n<p>Rippe (roh und fleischig):&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 5000 mg&nbsp; CA \/100 g<\/p>\n\n\n\n<p>Brustbein (roh und fleischig):&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 3000&nbsp;mg&nbsp; CA \/100 g<\/p>\n\n\n\n<p>Gefl\u00fcgelknochen (roh und fleischig): 2000&nbsp;mg&nbsp; CA \/100 g<\/p>\n\n\n\n<p>Karkasse (roh und fleischig)&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp;&nbsp; 1000 mg CA \/100g<\/p>\n\n\n\n<p>Fleischknochenmehl mit Ca-Ph 2:1<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Nicht f\u00fcttern: Tragende Knochen von Gro\u00dftieren und Markknochen<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/leg-disk-6066_1280-2-2-300x200.jpg\" alt=\"\" class=\"wp-image-12661\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/leg-disk-6066_1280-2-2-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/leg-disk-6066_1280-2-2-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/leg-disk-6066_1280-2-2.jpg 756w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Tragende Knochen sind Beinknochen. Diese sollten nicht gef\u00fcttert werden, weil sie extrem hart sind und die Z\u00e4hne kaputt machen. Ausnahmen bilden die tragenden Knochen von Kleintieren unter Putengr\u00f6\u00dfe, wie Huhn und Kaninchen. Diese k\u00f6nnen verf\u00fcttert werden.<\/p>\n\n\n\n<p>Auch die in der Hundef\u00fctterung beliebten Markknochen geh\u00f6ren zu den tragenden Knochen. Markknochen sind runde, mit Knochenmark gef\u00fcllte, hohle Scheiben des Beinknochens. Sie sind zum einen zahnsch\u00e4dlich, aufgrund ihrer H\u00e4rte. Zum anderen kann der Hund sich den runden, hohlen Knochen um den Unterkiefer wickeln und sich schwer verletzen. Markknochen sind ein No-Go in der Hundef\u00fctterung.<\/p>\n\n\n\n<p>Ausnahme: Nur das Knochenmark verf\u00fcttern, durch vorherigen Auskratzen oder Auskochen.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Nicht f\u00fcttern: H\u00e4lse und Kehlk\u00f6pfe<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/food-photography-675564_1920-2-1-300x200.jpg\" alt=\"\" class=\"wp-image-12663\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-photography-675564_1920-2-1-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-photography-675564_1920-2-1-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-photography-675564_1920-2-1.jpg 756w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Ich pers\u00f6nlich f\u00fcttere nichts aus dem Halsbereich, aufgrund der M\u00f6glichkeit, dass Schilddr\u00fcse mitgefressen wird. Ich selbst hab Schilddr\u00fcsenprobleme und wei\u00df, was ein Zuviel an \u201eStoff\u201c bewirken kann. Der ein oder andere Hals wird keinem Hund schaden. Von einer regelm\u00e4\u00dfigen F\u00fctterung w\u00fcrde ich jedoch abraten.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Nicht f\u00fcttern: Erhitzte Knochen<\/strong><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"193\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/food-3646780_1280-2-1-300x193.jpg\" alt=\"\" class=\"wp-image-12665\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-3646780_1280-2-1-300x193.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-3646780_1280-2-1.jpg 670w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Erhitzte Knochen zu f\u00fcttern ist absolut tabu. Egal, ob gekocht, gebacken oder gegrillt. Sie splittern und k\u00f6nnen den Hund innerlich leicht und schwer verletzen.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h5 class=\"wp-block-heading\">Kausnacks<\/h5>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"835\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/bb-scaled.jpg\" alt=\"\" class=\"wp-image-12600\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/bb-scaled.jpg 2560w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/bb-300x98.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/bb-1024x334.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/bb-768x250.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/bb-1536x501.jpg 1536w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/bb-2048x668.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div>\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>Hunde haben ein nat\u00fcrliches Kaubed\u00fcrfnis. Diese Begr\u00fcndung allein reicht aus, um zu verdeutlichen, dass wir diesem Bed\u00fcrfnis gerecht werden m\u00fcssen. Hunde wollen kauen und sollen kauen. Kauen macht Spa\u00df. Kauen besch\u00e4ftigt. Kauen beruhigt. Kauen st\u00e4rkt das Gebiss und reinigt die Z\u00e4hne.<\/p>\n\n\n\n<p>Meine Hunde d\u00fcrfen 4 x die Woche kauen. Mehr halten die Hosen nicht aus. Und das Portemonnaie.<\/p>\n\n\n\n<p>Sonntags kauen sie zum Fr\u00fchst\u00fcck an ihrem rohen, fleischigen Knochen. Mo\/Mi\/Fr kauen sie an einem Kausnack, welchen ich ihnen 2 &#8211; 3 Stunden nach dem Abendessen gebe.<\/p>\n\n\n\n<p>Ich achte darauf, dass der Kausnack nat\u00fcrlichen Ursprungs ist und ihnen Kauspa\u00df von mindestens 20 Minuten erm\u00f6glicht. Gerne auch mal 60, wenn die Qualit\u00e4t stimmt.<\/p>\n\n\n\n<p>Ich nutze fast ausschlie\u00dflich Rinderkopfhaut, Ochsenziemer und Rinderohren mit Fell.<\/p>\n\n\n\n<p>Wer Welpen, Minihunde oder Hunde mit schlechten Z\u00e4hnen hat, kann auf Kaninchenohren, H\u00fchnerf\u00fc\u00dfe, Pansen und \u00e4hnliches weiches Zeugs zur\u00fcckgreifen. Gro\u00dfe Hunde atmen diese Snacks jedoch in 10 Sekunden weg. F\u00fcr uns verschwendete Kalorien, ohne jeglichen Mehrwert f\u00fcr den gro\u00dfen, aktiven Kauer.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Nicht empfehlenswert:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Schweineohren (k\u00f6nnen, wenn auch sehr selten, das f\u00fcr Hunde t\u00f6dliche Aujeszky-Virus enthalten)<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"199\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/Unbenannt-2-300x199.jpg\" alt=\"\" class=\"wp-image-12669\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Unbenannt-2-300x199.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Unbenannt-2-1024x679.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Unbenannt-2-768x509.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Unbenannt-2-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Unbenannt-2.jpg 1182w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Hufe, Geweih, Holz, Kauwurzel (Splittergefahr und extrem scharfkantig)<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"204\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/Unbenannt-2-2-300x204.jpg\" alt=\"\" class=\"wp-image-12673\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Unbenannt-2-2-300x204.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Unbenannt-2-2-768x521.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/Unbenannt-2-2.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Getrocknete Schinkenknochen (verursachten bei uns behandlungsbed\u00fcrftige Verstopfung und extrem scharfkantig)<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"183\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/t-bone-gristle-1238297_1920-2-300x183.jpg\" alt=\"\" class=\"wp-image-12675\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/t-bone-gristle-1238297_1920-2-300x183.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/t-bone-gristle-1238297_1920-2-1024x623.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/t-bone-gristle-1238297_1920-2-768x467.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/t-bone-gristle-1238297_1920-2.jpg 1500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<ul class=\"wp-block-list\"><li>Jegliche k\u00fcnstliche Kauknochen oder verarbeitete Rinderhaut in typischer Knochenform (meist in China hergestellt und stark mit Giftstoffen belastet)<\/li><\/ul>\n\n\n\n<figure class=\"wp-block-image\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"225\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/dog-bones-350094_1920-2-300x225.jpg\" alt=\"\" class=\"wp-image-12677\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/dog-bones-350094_1920-2-300x225.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/dog-bones-350094_1920-2-1024x768.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/dog-bones-350094_1920-2-768x576.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/dog-bones-350094_1920-2.jpg 1400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>Wichtig ist, wie beim generellen F\u00fcttern auch, anwesend zu sein. Sollte doch mal ein St\u00fcck Kauknochen im Zahn oder Hals stecken bleiben, muss der Besitzer sofort Hilfe leisten k\u00f6nnen.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Kohlenhydrate<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1001\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04352.jpg\" alt=\"\" class=\"wp-image-12602\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04352.jpg 1500w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04352-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04352-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04352-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04352-360x240.jpg 360w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n<\/div>\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Die meisten Hunderassen k\u00f6nnen, d\u00fcrfen und sollen Kohlenhydrate verdauen. <\/h5>\n\n\n\n<p>Ihre Verdauung hat sich an den Allesfresser Mensch angepasst.<\/p>\n\n\n\n<p>Doch nicht alle Kohlenhydrate, welche der Mensch sich jemals einverleibte, sind artgerecht. Weder f\u00fcr Mensch noch Hund. Brot, Nudeln, Pizza und Pasta sind leere, tote, krankmachende Kohlenhydrate. Das heutige auf Hochleistung und N\u00e4hrstoffarmut gez\u00fcchtete Getreide geh\u00f6rt dazu. Wir f\u00fcttern kein Getreide in jedweder Form. Es bietet einfach keine Vorteile. Nur Nachteile.<\/p>\n\n\n\n<p>Zu den sinnvollen, lebendigen, kohlenhydrathaltigen Lebensmitteln z\u00e4hlt vor allem Gem\u00fcse.<\/p>\n\n\n\n<p>St\u00e4rkehaltiges Gem\u00fcse f\u00fcr den Energieaufbau. St\u00e4rkearmes Gem\u00fcse als Ballaststofflieferant und Mineralstoffquelle.<\/p>\n\n\n\n<p>Obst bekommen meine Hunde nicht. H\u00f6chstens als Resteverwerter, falls mal eine braune Banane liegen bleibt oder die Str\u00e4ucher Beeren tragen. Ansonsten enth\u00e4lt Obst mir zu viel Zucker.<\/p>\n\n\n\n<p>Unser Gem\u00fcseanteil enth\u00e4lt 50 % st\u00e4rkereiches und 50 % st\u00e4rkearmes Gem\u00fcse. So bleiben wir im Low Carb Bereich, halten den Insulinspiegel stabil und haben einen hohen Ballaststoffanteil im Futter.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"1500\" height=\"1001\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/DSC04377.jpg\" alt=\"\" class=\"wp-image-12604\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04377.jpg 1500w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04377-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04377-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04377-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/DSC04377-360x240.jpg 360w\" sizes=\"auto, (max-width: 1500px) 100vw, 1500px\" \/><\/figure>\n<\/div>\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>An kohlenhydratreichem Gem\u00fcse nutzen wir:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>S\u00fc\u00dfkartoffeln 20 g\u00a0 KH \/ 100 g<\/li><li>Kartoffeln 15 g\u00a0 KH \/ 100 g<\/li><li>Pastinaken 12 g\u00a0 KH \/ 100 g<\/li><li>Hokkaido 12 g\u00a0 KH \/ 100 g<\/li><li>Butternut 12 g\u00a0 KH \/ 100 g<\/li><\/ul>\n\n\n\n<p><strong>An kohlenhydratarmen Gem\u00fcse nutzen wir:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Karotten 8 g\u00a0 KH \/ 100 g<\/li><li>Rote Beete 8 g\u00a0 KH \/ 100 g<\/li><li>Wurzelpetersilie 5 g\u00a0 KH \/ 100 g<\/li><li>Spargel 4 g\u00a0 KH \/ 100 g<\/li><li>Kohlrabi 4 g\u00a0 KH \/ 100 g<\/li><li>Zucchini 3 g\u00a0 KH \/ 100 g<\/li><li>Brokkoli \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a03 g\u00a0 KH \/ 100 g<\/li><li>Gr\u00fcne Bohnen 3 g\u00a0 KH \/ 100 g<\/li><li>Gr\u00fcnkohl 3 g\u00a0 KH \/ 100 g<\/li><li>Sellerie 3 g\u00a0 KH \/ 100 g<\/li><li>Blumenkohl 2 g\u00a0 KH \/100 g<\/li><li>Gurke 2 g\u00a0 KH \/ 100 g<\/li><li>Fenchel 2 g\u00a0 KH \/ 100 g<\/li><li>Salat \u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a02 g\u00a0 KH \/ 100 g<\/li><\/ul>\n\n\n\n<p>Hinzukommen Kr\u00e4uter in kleinen Mengen, je nach Verf\u00fcgbarkeit. Petersilie, Basilikum, Lavendel, Rosmarin, Kamille etc.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p><strong>Bitte bedenken:<\/strong><\/p>\n\n\n\n<p>Hunde k\u00f6nnen p\u00fcriertes Gem\u00fcse am besten verwerten.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img loading=\"lazy\" decoding=\"async\" width=\"2560\" height=\"835\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/vvv-scaled.jpg\" alt=\"\" class=\"wp-image-12606\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/vvv-scaled.jpg 2560w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/vvv-300x98.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/vvv-1024x334.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/vvv-768x250.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/vvv-1536x501.jpg 1536w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/vvv-2048x668.jpg 2048w\" sizes=\"auto, (max-width: 2560px) 100vw, 2560px\" \/><\/figure>\n<\/div>\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p>Ich werfe es morgens in den Topf, koche es eine halbe Stunde, zerstampfe es mit der Gabel, fette es und lass es bis abends auf dem Herd stehen. Dann bekommen sie es zimmerwarm.<\/p>\n\n\n\n<p>Grunds\u00e4tzlich zerkleinere ich die Lebensmittel erst nach dem Kochen, damit m\u00f6glich wenig N\u00e4hrstoffe ans Wasser verloren gehen.<\/p>\n\n\n\n<p>W\u00e4re ich sesshaft, w\u00fcrde ich einen Monatsvorrat kochen und in einer monstr\u00f6sen Tiefk\u00fchltruhe einfrieren.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h3 class=\"wp-block-heading\">Fett<\/h3>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"alignleft\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/vagabondogs.me\/\/wp-content\/uploads\/2022\/08\/food-3179853_1920-2-300x200.jpg\" alt=\"\" class=\"wp-image-12682\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-3179853_1920-2-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-3179853_1920-2-1024x683.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-3179853_1920-2-768x512.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-3179853_1920-2-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/08\/food-3179853_1920-2.jpg 1414w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n\n\n<p>Das Gewicht meiner Hunde reguliere ich mit dem zugesetzten Fettanteil.<\/p>\n\n\n\n<p>Nicht \u00fcber die Wegnahme oder Zugabe von Fleisch und Gem\u00fcse, denn dieses dient im Erhaltungsbedarf ihrer Grundversorgung mit N\u00e4hrstoffen und nur indirekt der Figurplanung.<\/p>\n\n\n\n<p>Dabei fette ich nach Gef\u00fchl und Augenma\u00df. Ich gebe im Erhaltungsbedarf etwa 15 &#8211; 25 g Fett pro Hund ins abendliche Gem\u00fcse.<\/p>\n\n\n\n<p>Im tiefen Winter etwas mehr, da sie durch die K\u00e4lte einen h\u00f6heren Verbrauch haben.<\/p>\n\n\n\n<p>An hei\u00dfen Sommertagen etwas weniger, da sie sich bei Hitze weniger bewegen.<\/p>\n\n\n\n<p>Waren sie also 6 Stunden bei 2 Grad an der Nordsee unterwegs, wird mehr Fett gef\u00fcttert.<\/p>\n\n\n\n<p>Lagen sie den ganzen Tag bei 25 Grad unterm Apfelbaum, wird weniger Fett gef\u00fcttert.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<p><strong>An Fett nutze ich, je nach Verf\u00fcgbarkeit:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>Frisches Tierfett<\/li><li>Rindertalg<\/li><li>G\u00e4nseschmalz<\/li><li>Butter<\/li><li>Ghee<\/li><li>Oliven\u00f6l<\/li><\/ul>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Nahrungserg\u00e4nzungsmittel (NEM)<\/h4>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/11\/DSC00127klein-3-1024x684.jpg\" alt=\"\" class=\"wp-image-13765\" srcset=\"https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/11\/DSC00127klein-3-1024x684.jpg 1024w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/11\/DSC00127klein-3-300x200.jpg 300w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/11\/DSC00127klein-3-768x513.jpg 768w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/11\/DSC00127klein-3-1536x1025.jpg 1536w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/11\/DSC00127klein-3-360x240.jpg 360w, https:\/\/vagabondogs.me\/wp-content\/uploads\/2022\/11\/DSC00127klein-3.jpg 2000w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<p>Ich bin bekennender Ma\u00dfen ein Fan von Nahrungserg\u00e4nzungsmitteln, im Sinne der wissenschaftlich fundierten Orthomolekularmedizin.<\/p>\n\n\n\n<p>Ich bin kein Fan der Hom\u00f6opathie, also bitte nicht verwechseln.<\/p>\n\n\n\n<p>Im Idealfall werden alle Vitalstoffe \u00fcber die Nahrung gedeckt. Dies ist nicht immer m\u00f6glich. Ob erg\u00e4nzt werden muss, kann ganz einfach herausgefunden werden.<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><strong>Die Devise hei\u00dft: \u00dcberpr\u00fcfen, Messen und Auff\u00fcllen.<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\"><li>\u00dcberpr\u00fcfen, was in der t\u00e4glichen Nahrung vorhanden ist.<\/li><li>Messen, was im Blut ankommt.<\/li><li>Auff\u00fcllen, was fehlt.<\/li><\/ul>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Unsere pers\u00f6nliche Futteranalyse hat ergeben, dass fast alle Vitamine \u00fcber die Nahrung gedeckt sind, jedoch nicht alle Mineralstoffe und Spurenelemente.<\/p>\n\n\n\n<p>Wir erg\u00e4nzen, Vitamin D + K2, Magnesium, Omega 3, Jod, Vitamin E, Zink und Eisen.<\/p>\n\n\n\n<p>Auch Vitamin C kommt bei uns zum Einsatz. Zwar k\u00f6nnen Hunde Vitamin C selbst bilden, jedoch nur dann, wenn alle Co Faktoren vorhanden sind und der Darm perfekt funktioniert. Diese Vitamin C Synthese ist im Krankheitsfall, zu stressigen Zeiten oder im Alter eingeschr\u00e4nkt. Daher erg\u00e4nzen wir bei Bedarf mit 0,5 \u2013 1g pro Hund und Tag. Bei Krankheit supplementieren wir au\u00dferdem 50 \u00b5g Selen dazu, da der Bedarf steigt und unsere Nahrungsmittel gerade einmal den Tagesbedarf decken. <\/p>\n\n\n\n<p>Wir nutzen kein All in One Pr\u00e4parat, sondern kaufen die N\u00e4hrstoffe einzeln, damit wir sie perfekt dosieren k\u00f6nnen und freie Hand \u00fcber die N\u00e4hrstoffverbindungen haben.<\/p>\n\n\n\n<p>Wer selbst f\u00fcr den Hund kocht, sollte sich verpflichtender Weise in die Thematik einlesen.<\/p>\n\n\n\n<p>Denn es gibt bestimmte Stoffe, welche nicht \u00fcber normale Nahrung gedeckt werden k\u00f6nnen und zwangsweise erg\u00e4nzt werden m\u00fcssen, wie zum Beispiel Vitamin D.<\/p>\n\n\n\n<p>Doch auch bei Fertigfutter lohnt ein Blick auf die zugesetzten Stoffe. Diese sind nicht selten unterdosiert, fehlen teilweise g\u00e4nzlich oder liegen in einer schlecht verdaulichen Form vor.<\/p>\n\n\n\n<p>F\u00fcrs Protokoll: Ich bin keine Tier\u00e4rztin und beschreibe nur, was ich meinen Hunden gebe.\u00a0Die richtige Erg\u00e4nzung f\u00fcr meine Hunde kann f\u00fcr andere Hunde unpassend sein. Bitte nicht einfach nachmachen, sondern bei jeglichen Zweifeln eine Fachkraft zu Rate ziehen bzw. in Absprache mit dem ern\u00e4hrungskundigen Tierarzt, lieber zu einem Fertigpr\u00e4parat greifen, bis ausreichend Wissen f\u00fcrs selbstst\u00e4ndige Dosieren vorhanden ist.<\/p>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">\u00dcbersicht<\/h4>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>Gesamtfuttermenge<\/strong><\/p>\n\n\n\n<p>4 % \/ K\u00f6rpergewicht \/ Tag<\/p>\n\n\n\n<p><strong>Zusammensetzung <\/strong><\/p>\n\n\n\n<p>50 % tierisch, 50 % pflanzlich<\/p>\n\n\n\n<p><strong>Fr\u00fchst\u00fcck<\/strong><\/p>\n\n\n\n<p>4x\/Woche Muskelfleisch (mind. 2x rot, max. 2x wei\u00df)<\/p>\n\n\n\n<p>1x\/Woche Organe (mind. 50&nbsp;% Leber, max. 50 % Milz, Niere oder Herz)<\/p>\n\n\n\n<p>1x\/Woche Rohe fleischige Knochen<\/p>\n\n\n\n<p>1x\/Woche Ei<\/p>\n\n\n\n<p><strong>Abendessen<\/strong><\/p>\n\n\n\n<p>50 % kohlenhydratreiches Gem\u00fcse, 50 % kohlenhydratarmes Gem\u00fcse, Fett<\/p>\n\n\n\n<p><strong>Kausnacks<\/strong><\/p>\n\n\n\n<p><strong>&nbsp;<\/strong>3x\/Woche&nbsp;Rinderkopfhaut, Ochsenziemer oder Rinderohren mit Fell.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>NEM Morgens<\/strong><\/p>\n\n\n\n<p>Vitamin D + K2<\/p>\n\n\n\n<p>Magnesium<\/p>\n\n\n\n<p>Omega 3<\/p>\n\n\n\n<p>Jod<\/p>\n\n\n\n<p>Vitamin E<\/p>\n\n\n\n<p>Bei Bedarf Vitamin C<\/p>\n\n\n\n<p>Bei bedarf Selen<\/p>\n\n\n\n<p><strong>NEM Abends<\/strong><\/p>\n\n\n\n<p>Magnesium<\/p>\n\n\n\n<p>Zink<\/p>\n\n\n\n<p>Eisen<\/p>\n\n\n\n<p>Bei Bedarf Vitamin C<\/p>\n\n\n\n<p>Bei Bedarf Natrium<\/p>\n<\/div>\n<\/div>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">Essplan<\/h4>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-regular\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\"><\/th><th class=\"has-text-align-center\" data-align=\"center\">Mo<\/th><th class=\"has-text-align-center\" data-align=\"center\">Di<\/th><th class=\"has-text-align-center\" data-align=\"center\">Mi<\/th><th class=\"has-text-align-center\" data-align=\"center\">Do<\/th><th class=\"has-text-align-center\" data-align=\"center\">Fr<\/th><th class=\"has-text-align-center\" data-align=\"center\">Sa<\/th><th class=\"has-text-align-center\" data-align=\"center\">So<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><em>Morgens<\/em><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Muskelfleisch<\/td><td class=\"has-text-align-center\" data-align=\"center\">Muskelfleisch<\/td><td class=\"has-text-align-center\" data-align=\"center\">Ei<\/td><td class=\"has-text-align-center\" data-align=\"center\">Organe<\/td><td class=\"has-text-align-center\" data-align=\"center\">Muskelfleisch<\/td><td class=\"has-text-align-center\" data-align=\"center\">Muskelfleisch<\/td><td class=\"has-text-align-center\" data-align=\"center\">Rohe<br>fleischige<br>Knochen<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><em>Abends<\/em><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">Gem\u00fcse<br>Fett<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gem\u00fcse<br>Fett<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gem\u00fcse<br>Fett<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gem\u00fcse<br>Fett<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gem\u00fcse<br>Fett<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gem\u00fcse<br>Fett<\/td><td class=\"has-text-align-center\" data-align=\"center\">Gem\u00fcse<br>Fett<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\"><strong><em>Kausnack<\/em><\/strong><\/td><td class=\"has-text-align-center\" data-align=\"center\">X<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\">X<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\">X<\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><td class=\"has-text-align-center\" data-align=\"center\"><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<hr class=\"wp-block-separator has-alpha-channel-opacity is-style-wide\"\/>\n\n\n\n<h4 class=\"wp-block-heading\">NEM Plan<\/h4>\n\n\n\n<p>&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-table\"><table class=\"has-fixed-layout\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Morgens<\/th><th class=\"has-text-align-center\" data-align=\"center\">Abends<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">Vitamin D 2500 IE (Tia t\u00e4glich, Sandy Mo-Fr)<br>Vitamin K2 50 mcg (Tia t\u00e4glich, Sandy Mo-Fr)<br>Magnesium 100 mg (t\u00e4glich)<br>Jod 200 mcg (t\u00e4glich)<br>Omega 3 5ml (Mo, Mi, Fr)<br>Vitamin E 70 mg (Mo, Mi, Fr)<br>500 mg Vitamin C (bei Krankheit)<br>50 \u00b5g Selen (bei Krankheit)<\/td><td class=\"has-text-align-center\" data-align=\"center\">Zink 12 mg (t\u00e4glich)<br>Magnesium 100 mg (t\u00e4glich)<br>Eisen 20 mg (Mo, Mi, Fr vor dem Schlafengehen)<br>500 mg Vitamin C (bei Krankheit)<br>Salz (wetter-\/aktivit\u00e4ts-abh\u00e4ngig)<\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"epyt-video-wrapper\"><iframe loading=\"lazy\"  id=\"_ytid_64006\"  width=\"750\" height=\"421\"  data-origwidth=\"750\" data-origheight=\"421\"  data-relstop=\"1\" src=\"https:\/\/www.youtube.com\/embed\/W_UVqGSXJew?enablejsapi=1&#038;autoplay=0&#038;cc_load_policy=0&#038;cc_lang_pref=&#038;iv_load_policy=1&#038;loop=0&#038;rel=0&#038;fs=1&#038;playsinline=0&#038;autohide=2&#038;theme=dark&#038;color=red&#038;controls=1&#038;disablekb=0&#038;\" class=\"__youtube_prefs__  epyt-is-override  no-lazyload\" title=\"YouTube player\"  allow=\"fullscreen; accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen data-no-lazy=\"1\" data-skipgform_ajax_framebjll=\"\"><\/iframe><\/div>\n<\/div><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Das richtige Hundefutter ist DIE Grundlage der Hundegesundheit. Nicht nur der k\u00f6rperlichen. Auch der psychischen. Und sogar der erzieherischen. Denn je besser der Hund mit allen N\u00e4hrstoffen versorgt ist, desto souver\u00e4ner kann sein Nervensystem mit Stressfaktoren umgehen und \u00fcberschie\u00dfende Reaktionen ausgleichen. Ein Mangel an bestimmten N\u00e4hrstoffen &#8211; kann und wird [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13111,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-12578","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert"],"_links":{"self":[{"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/posts\/12578","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/comments?post=12578"}],"version-history":[{"count":207,"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/posts\/12578\/revisions"}],"predecessor-version":[{"id":13802,"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/posts\/12578\/revisions\/13802"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/media\/13111"}],"wp:attachment":[{"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/media?parent=12578"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/categories?post=12578"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/vagabondogs.me\/de\/wp-json\/wp\/v2\/tags?post=12578"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}